{"id":27036,"date":"2025-01-17T12:55:28","date_gmt":"2025-01-17T11:55:28","guid":{"rendered":"https:\/\/sosa.several.studio\/producto\/sucre-a-glacer\/"},"modified":"2026-04-17T15:18:13","modified_gmt":"2026-04-17T13:18:13","slug":"sucre-glace-en-poudre","status":"publish","type":"producto","link":"https:\/\/www.sosa.cat\/fr\/produit\/sucre-glace-en-poudre\/","title":{"rendered":"SUCRE GLACE EN POUDRE"},"content":{"rendered":"","protected":false},"featured_media":0,"parent":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"categoria-producto":[687,686],"certificacion":[],"garantia":[],"class_list":["post-27036","producto","type-producto","status-publish","hentry","categoria-producto-sucres-techniques-et-edulcorants","categoria-producto-sucres-techniques"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SUCRE GLACE EN POUDRE - Sosa<\/title>\n<meta name=\"description\" content=\"Le sucre glace en poudre est un m\u00e9lange de saccharose et de f\u00e9cule de ma\u00efs, finement broy\u00e9 pour obtenir une texture lisse et homog\u00e8ne.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sosa.cat\/fr\/produit\/sucre-glace-en-poudre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SUCRE GLACE EN POUDRE - Sosa\" \/>\n<meta property=\"og:description\" content=\"Le sucre glace en poudre est un m\u00e9lange de saccharose et de f\u00e9cule de ma\u00efs, finement broy\u00e9 pour obtenir une texture lisse et homog\u00e8ne.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sosa.cat\/fr\/produit\/sucre-glace-en-poudre\/\" \/>\n<meta property=\"og:site_name\" content=\"Sosa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SosaIngredients\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-17T13:18:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sosa.cat\/wp-content\/uploads\/2025\/01\/share-sosa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sosa.cat\\\/fr\\\/produit\\\/sucre-glace-en-poudre\\\/\",\"url\":\"https:\\\/\\\/www.sosa.cat\\\/fr\\\/produit\\\/sucre-glace-en-poudre\\\/\",\"name\":\"SUCRE GLACE EN POUDRE - Sosa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sosa.cat\\\/#website\"},\"datePublished\":\"2025-01-17T11:55:28+00:00\",\"dateModified\":\"2026-04-17T13:18:13+00:00\",\"description\":\"Le sucre glace en poudre est un m\u00e9lange de saccharose et de f\u00e9cule de ma\u00efs, finement broy\u00e9 pour obtenir une texture lisse et homog\u00e8ne.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sosa.cat\\\/fr\\\/produit\\\/sucre-glace-en-poudre\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sosa.cat\\\/fr\\\/produit\\\/sucre-glace-en-poudre\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sosa.cat\\\/fr\\\/produit\\\/sucre-glace-en-poudre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.sosa.cat\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/www.sosa.cat\\\/producto\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sucres techniques\",\"item\":\"https:\\\/\\\/www.sosa.cat\\\/fr\\\/categorie-produit\\\/sucres-techniques\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Sucres Techniques et \u00c9dulcorants\",\"item\":\"https:\\\/\\\/www.sosa.cat\\\/fr\\\/categorie-produit\\\/sucres-techniques\\\/sucres-techniques-et-edulcorants\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"SUCRE GLACE EN POUDRE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sosa.cat\\\/#website\",\"url\":\"https:\\\/\\\/www.sosa.cat\\\/\",\"name\":\"Sosa Ingredients\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sosa.cat\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sosa.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sosa.cat\\\/#organization\",\"name\":\"SOSA\",\"url\":\"https:\\\/\\\/www.sosa.cat\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.sosa.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sosa.cat\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo_sosa_big.png\",\"contentUrl\":\"https:\\\/\\\/www.sosa.cat\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo_sosa_big.png\",\"width\":258,\"height\":260,\"caption\":\"SOSA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sosa.cat\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SosaIngredients\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sosaingredients\\\/\",\"https:\\\/\\\/www.youtube.com\\\/SosaIngredients\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sosa-ingredients\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SUCRE GLACE EN POUDRE - Sosa","description":"Le sucre glace en poudre est un m\u00e9lange de saccharose et de f\u00e9cule de ma\u00efs, finement broy\u00e9 pour obtenir une texture lisse et homog\u00e8ne.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sosa.cat\/fr\/produit\/sucre-glace-en-poudre\/","og_locale":"fr_FR","og_type":"article","og_title":"SUCRE GLACE EN POUDRE - Sosa","og_description":"Le sucre glace en poudre est un m\u00e9lange de saccharose et de f\u00e9cule de ma\u00efs, finement broy\u00e9 pour obtenir une texture lisse et homog\u00e8ne.","og_url":"https:\/\/www.sosa.cat\/fr\/produit\/sucre-glace-en-poudre\/","og_site_name":"Sosa","article_publisher":"https:\/\/www.facebook.com\/SosaIngredients\/","article_modified_time":"2026-04-17T13:18:13+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.sosa.cat\/wp-content\/uploads\/2025\/01\/share-sosa.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sosa.cat\/fr\/produit\/sucre-glace-en-poudre\/","url":"https:\/\/www.sosa.cat\/fr\/produit\/sucre-glace-en-poudre\/","name":"SUCRE GLACE EN POUDRE - Sosa","isPartOf":{"@id":"https:\/\/www.sosa.cat\/#website"},"datePublished":"2025-01-17T11:55:28+00:00","dateModified":"2026-04-17T13:18:13+00:00","description":"Le sucre glace en poudre est un m\u00e9lange de saccharose et de f\u00e9cule de ma\u00efs, finement broy\u00e9 pour obtenir une texture lisse et homog\u00e8ne.","breadcrumb":{"@id":"https:\/\/www.sosa.cat\/fr\/produit\/sucre-glace-en-poudre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sosa.cat\/fr\/produit\/sucre-glace-en-poudre\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sosa.cat\/fr\/produit\/sucre-glace-en-poudre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.sosa.cat\/fr\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/www.sosa.cat\/producto\/"},{"@type":"ListItem","position":3,"name":"Sucres techniques","item":"https:\/\/www.sosa.cat\/fr\/categorie-produit\/sucres-techniques\/"},{"@type":"ListItem","position":4,"name":"Sucres Techniques et \u00c9dulcorants","item":"https:\/\/www.sosa.cat\/fr\/categorie-produit\/sucres-techniques\/sucres-techniques-et-edulcorants\/"},{"@type":"ListItem","position":5,"name":"SUCRE GLACE EN POUDRE"}]},{"@type":"WebSite","@id":"https:\/\/www.sosa.cat\/#website","url":"https:\/\/www.sosa.cat\/","name":"Sosa Ingredients","description":"","publisher":{"@id":"https:\/\/www.sosa.cat\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sosa.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.sosa.cat\/#organization","name":"SOSA","url":"https:\/\/www.sosa.cat\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sosa.cat\/#\/schema\/logo\/image\/","url":"https:\/\/www.sosa.cat\/wp-content\/uploads\/2024\/11\/logo_sosa_big.png","contentUrl":"https:\/\/www.sosa.cat\/wp-content\/uploads\/2024\/11\/logo_sosa_big.png","width":258,"height":260,"caption":"SOSA"},"image":{"@id":"https:\/\/www.sosa.cat\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SosaIngredients\/","https:\/\/www.instagram.com\/sosaingredients\/","https:\/\/www.youtube.com\/SosaIngredients","https:\/\/www.linkedin.com\/company\/sosa-ingredients\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.sosa.cat\/fr\/wp-json\/wp\/v2\/producto\/27036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sosa.cat\/fr\/wp-json\/wp\/v2\/producto"}],"about":[{"href":"https:\/\/www.sosa.cat\/fr\/wp-json\/wp\/v2\/types\/producto"}],"version-history":[{"count":1,"href":"https:\/\/www.sosa.cat\/fr\/wp-json\/wp\/v2\/producto\/27036\/revisions"}],"predecessor-version":[{"id":63305,"href":"https:\/\/www.sosa.cat\/fr\/wp-json\/wp\/v2\/producto\/27036\/revisions\/63305"}],"wp:attachment":[{"href":"https:\/\/www.sosa.cat\/fr\/wp-json\/wp\/v2\/media?parent=27036"}],"wp:term":[{"taxonomy":"categoria-producto","embeddable":true,"href":"https:\/\/www.sosa.cat\/fr\/wp-json\/wp\/v2\/categoria-producto?post=27036"},{"taxonomy":"certificacion","embeddable":true,"href":"https:\/\/www.sosa.cat\/fr\/wp-json\/wp\/v2\/certificacion?post=27036"},{"taxonomy":"garantia","embeddable":true,"href":"https:\/\/www.sosa.cat\/fr\/wp-json\/wp\/v2\/garantia?post=27036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}